{"id":1057,"date":"2024-03-31T22:05:30","date_gmt":"2024-03-31T22:05:30","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=1057"},"modified":"2026-06-29T13:30:39","modified_gmt":"2026-06-29T18:30:39","slug":"sucedio-en-los-70s-8","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/1057","title":{"rendered":"Sucedi\u00f3 en los 70s &#8211; 8"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/xaqp16.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p> \u00abSucedi\u00f3 en los 70s &#8211; 8\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-1057-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio96\/sucedioenlos70s_8.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio96\/sucedioenlos70s_8.mp3\">http:\/\/www.archive.org\/download\/AQPRadio96\/sucedioenlos70s_8.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSucedi\u00f3 en los 70s &#8211; 8\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-1057","post","type-post","status-publish","format-standard","hentry","category-sucedio-en-los"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=1057"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1057\/revisions"}],"predecessor-version":[{"id":87111,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1057\/revisions\/87111"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=1057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=1057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=1057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}