{"id":1092,"date":"2024-05-24T20:23:24","date_gmt":"2024-05-24T20:23:24","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=1092"},"modified":"2026-06-29T13:29:10","modified_gmt":"2026-06-29T18:29:10","slug":"mini-mix-soul-3","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/1092","title":{"rendered":"Mini Mix Soul \u2013 3"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.hola.com\/imagenes\/viajes\/2014072572733\/top-25-destinos-turisticos-mundo\/0-281-710\/a_sidne-a.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abMini Mix Soul &#8211; 3\u00bb <\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-1092-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/Radio_AQP_2\/xraqp3.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/Radio_AQP_2\/xraqp3.mp3\">http:\/\/www.archive.org\/download\/Radio_AQP_2\/xraqp3.mp3<\/a><\/audio>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMini Mix Soul &#8211; 3\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-1092","post","type-post","status-publish","format-standard","hentry","category-musica-disco-soul"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=1092"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1092\/revisions"}],"predecessor-version":[{"id":87011,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1092\/revisions\/87011"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=1092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=1092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=1092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}