{"id":10987,"date":"2023-06-02T02:27:23","date_gmt":"2023-06-02T02:27:23","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=10987"},"modified":"2026-08-12T21:10:57","modified_gmt":"2026-08-13T02:10:57","slug":"grupo-america-en-1971","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/10987","title":{"rendered":"Grupo Am\u00e9rica en 1971"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/_xQEKq4NA2tM\/SwRF3z8PgqI\/AAAAAAAACNk\/0Qjw4wm2chY\/s1600\/Grupo+Am%C3%A9rica.JPG\" alt=\"\" width=\"98%\" align=\"center\" \/><\/p>\n<p>\u00abGrupo Am\u00e9rica en 1971\u00bb <\/p>\n<p><strong>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-10987-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio448\/GrupoAmericaen1971.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio448\/GrupoAmericaen1971.mp3\">http:\/\/archive.org\/download\/AQPRadio448\/GrupoAmericaen1971.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>\u00abGrupo Am\u00e9rica en 1971\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-10987","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/10987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=10987"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/10987\/revisions"}],"predecessor-version":[{"id":100473,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/10987\/revisions\/100473"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=10987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=10987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=10987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}