{"id":11250,"date":"2023-03-23T22:03:57","date_gmt":"2023-03-23T22:03:57","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=11250"},"modified":"2026-06-29T17:58:11","modified_gmt":"2026-06-29T22:58:11","slug":"baul-de-los-recuerdos-disco-construction-hustle","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/11250","title":{"rendered":"Ba\u00fal de los Recuerdos &#8211; Disco Construction Hustle"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/2.bp.blogspot.com\/_gKZOnt57_6o\/TQKlgbqseZI\/AAAAAAAAARE\/4HvqTIvtWhA\/s1600\/a.JPG\" width=\"98%\" align=\"center\"><br \/>\n \u00abBa\u00fal de los Recuerdos &#8211; Disco Construction Hustle\u00bb <audio class=\"wp-audio-shortcode\" id=\"audio-11250-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio455\/BR_DiscoConstruction_Hustle.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio455\/BR_DiscoConstruction_Hustle.mp3\">http:\/\/archive.org\/download\/AQPRadio455\/BR_DiscoConstruction_Hustle.mp3<\/a><\/audio> <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBa\u00fal de los Recuerdos &#8211; Disco Construction Hustle\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-11250","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/11250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=11250"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/11250\/revisions"}],"predecessor-version":[{"id":88592,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/11250\/revisions\/88592"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=11250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=11250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=11250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}