{"id":1265,"date":"2024-04-25T16:09:18","date_gmt":"2024-04-25T16:09:18","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=1265"},"modified":"2026-06-29T13:29:50","modified_gmt":"2026-06-29T18:29:50","slug":"mix-los-beatles-en-todos-los-ritmos","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/1265","title":{"rendered":"Mix Los Beatles en todos los Ritmos"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/unamglobal.unam.mx\/wp-content\/uploads\/2024\/01\/internacional-beatles.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abMix Los Beatles en todos los Ritmos\u00bb <\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-1265-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio106\/Mix_LosBeatlesentodoslosritmos.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio106\/Mix_LosBeatlesentodoslosritmos.mp3\">http:\/\/www.archive.org\/download\/AQPRadio106\/Mix_LosBeatlesentodoslosritmos.mp3<\/a><\/audio>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Los Beatles en todos los Ritmos\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-1265","post","type-post","status-publish","format-standard","hentry","category-musica-disco-soul"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=1265"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1265\/revisions"}],"predecessor-version":[{"id":87065,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1265\/revisions\/87065"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=1265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=1265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=1265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}