{"id":13347,"date":"2023-02-10T12:55:50","date_gmt":"2023-02-10T12:55:50","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=13347"},"modified":"2026-08-12T21:23:18","modified_gmt":"2026-08-13T02:23:18","slug":"todo-mezclado-38","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/13347","title":{"rendered":"Todo Mezclado &#8211; 38"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/europaent3.files.wordpress.com\/2010\/04\/alcatraz.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n<p>\u00abTodo Mezclado &#8211; 38\u00bb <\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-13347-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio483\/Mix_Todomezclado38.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio483\/Mix_Todomezclado38.mp3\">http:\/\/archive.org\/download\/AQPRadio483\/Mix_Todomezclado38.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio \u00abTodo Mezclado &#8211; 38\u00bb<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-13347","post","type-post","status-publish","format-standard","hentry","category-todo-mezclado"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=13347"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13347\/revisions"}],"predecessor-version":[{"id":101302,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13347\/revisions\/101302"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=13347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=13347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=13347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}