{"id":13496,"date":"2025-11-16T14:48:07","date_gmt":"2025-11-16T19:48:07","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=13496"},"modified":"2026-06-29T10:47:37","modified_gmt":"2026-06-29T15:47:37","slug":"bert-kaempfert-en-1977","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/13496","title":{"rendered":"Bert Kaempfert en 1977"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/1AQPRadio_revive4.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abBert Kaempfert en 1977\u00bb  <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-13496-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio485_201503\/Mix_BertKaempfert_1977.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio485_201503\/Mix_BertKaempfert_1977.mp3\">http:\/\/archive.org\/download\/AQPRadio485_201503\/Mix_BertKaempfert_1977.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBert Kaempfert en 1977\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-13496","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=13496"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13496\/revisions"}],"predecessor-version":[{"id":83042,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13496\/revisions\/83042"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=13496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=13496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=13496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}