{"id":13590,"date":"2025-09-10T17:37:35","date_gmt":"2025-09-10T22:37:35","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=13590"},"modified":"2026-06-29T10:48:23","modified_gmt":"2026-06-29T15:48:23","slug":"mix-clasicos-bach","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/13590","title":{"rendered":"Mix Cl\u00e1sicos &#8211; Bach"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/DJ37.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abMix Cl\u00e1sicos &#8211; Bach\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-13590-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio489\/Mix_Clasicos_Bach.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio489\/Mix_Clasicos_Bach.mp3\">http:\/\/archive.org\/download\/AQPRadio489\/Mix_Clasicos_Bach.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Cl\u00e1sicos &#8211; Bach\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-13590","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=13590"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13590\/revisions"}],"predecessor-version":[{"id":83087,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/13590\/revisions\/83087"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=13590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=13590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=13590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}