{"id":14438,"date":"2023-02-15T10:30:27","date_gmt":"2023-02-15T10:30:27","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=14438"},"modified":"2026-06-22T11:29:04","modified_gmt":"2026-06-22T16:29:04","slug":"celia-cruz-boleros","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/14438","title":{"rendered":"Celia Cruz &#8211; Boleros"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/elegante6.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abCelia Cruz &#8211; Boleros\u00bb <\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-14438-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio503\/Mix_CeliaCruz_Boleros.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio503\/Mix_CeliaCruz_Boleros.mp3\">http:\/\/archive.org\/download\/AQPRadio503\/Mix_CeliaCruz_Boleros.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abCelia Cruz &#8211; Boleros\u00bb<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[71],"tags":[],"class_list":["post-14438","post","type-post","status-publish","format-standard","hentry","category-boleros"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/14438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=14438"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/14438\/revisions"}],"predecessor-version":[{"id":88855,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/14438\/revisions\/88855"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=14438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=14438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=14438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}