{"id":15912,"date":"2026-02-01T20:05:18","date_gmt":"2026-02-02T01:05:18","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=15912"},"modified":"2026-06-29T10:45:19","modified_gmt":"2026-06-29T15:45:19","slug":"hombres-g-master-mix","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/15912","title":{"rendered":"Hombres G &#8211; Master Mix"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/cdn-images.dzcdn.net\/images\/cover\/16c44205af69d33a82b5f75054a995b2\/1900x1900-000000-80-0-0.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abHombres G &#8211; Master Mix\u00bb <\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-15912-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio518\/Mix_HombresG_MasterMix.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio518\/Mix_HombresG_MasterMix.mp3\">http:\/\/archive.org\/download\/AQPRadio518\/Mix_HombresG_MasterMix.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abHombres G &#8211; Master Mix\u00bb<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-15912","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/15912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=15912"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/15912\/revisions"}],"predecessor-version":[{"id":82881,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/15912\/revisions\/82881"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=15912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=15912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=15912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}