{"id":16227,"date":"2024-09-13T04:46:05","date_gmt":"2024-09-13T04:46:05","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=16227"},"modified":"2026-06-29T13:19:57","modified_gmt":"2026-06-29T18:19:57","slug":"mix-romanticos-del-ayer-13","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/16227","title":{"rendered":"Mix Rom\u00e1nticos del Ayer &#8211; 13"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.copyright.gov\/music-modernization\/images\/licensing-interactive-streams.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abMix Rom\u00e1nticos del Ayer &#8211; 13\u00bb <\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-16227-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio528\/Mix_RomanticosdelAyer_13.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio528\/Mix_RomanticosdelAyer_13.mp3\">http:\/\/archive.org\/download\/AQPRadio528\/Mix_RomanticosdelAyer_13.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abMix Rom\u00e1nticos del Ayer &#8211; 13\u00bb<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-16227","post","type-post","status-publish","format-standard","hentry","category-baladas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/16227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=16227"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/16227\/revisions"}],"predecessor-version":[{"id":86475,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/16227\/revisions\/86475"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=16227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=16227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=16227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}