{"id":16384,"date":"2024-09-30T01:50:39","date_gmt":"2024-09-30T01:50:39","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=16384"},"modified":"2026-08-12T20:55:32","modified_gmt":"2026-08-13T01:55:32","slug":"the-three-degrees","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/16384","title":{"rendered":"The Three Degrees"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/jazzinphoto.files.wordpress.com\/2014\/03\/the-three-degrees-photo-by-echoesredferns-1975-chris-walter.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abThe Three Degrees\u00bb <\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-16384-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio532\/Mix_TheThreeDegrees.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio532\/Mix_TheThreeDegrees.mp3\">http:\/\/archive.org\/download\/AQPRadio532\/Mix_TheThreeDegrees.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abThe Three Degrees\u00bb<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-16384","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/16384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=16384"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/16384\/revisions"}],"predecessor-version":[{"id":98772,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/16384\/revisions\/98772"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=16384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=16384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=16384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}