{"id":17010,"date":"2024-10-31T02:32:01","date_gmt":"2024-10-31T02:32:01","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=17010"},"modified":"2026-06-29T13:13:47","modified_gmt":"2026-06-29T18:13:47","slug":"baul-de-los-recuerdos-the-shadows","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/17010","title":{"rendered":"Ba\u00fal de los Recuerdos &#8211; The Shadows"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/_tx6E6eeAvc0\/TUHw-OLmVeI\/AAAAAAAACyw\/Y8a7pOutMvE\/s1600\/front.jpg\" alt=\"\" width=\"98%\" align=\"middle\" \/><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abBa\u00fal de los Recuerdos &#8211; The Shadows\u00bb <\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-17010-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio538\/BR_TheShadows.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio538\/BR_TheShadows.mp3\">http:\/\/archive.org\/download\/AQPRadio538\/BR_TheShadows.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abBa\u00fal de los Recuerdos &#8211; The Shadows\u00bb<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-17010","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=17010"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17010\/revisions"}],"predecessor-version":[{"id":86128,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17010\/revisions\/86128"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=17010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=17010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=17010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}