{"id":17506,"date":"2024-12-03T00:59:45","date_gmt":"2024-12-03T00:59:45","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=17506"},"modified":"2026-08-12T20:51:12","modified_gmt":"2026-08-13T01:51:12","slug":"benjamin-rojas-y-su-piano-bar","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/17506","title":{"rendered":"Benjamin Rojas y su Piano Bar"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/is4-ssl.mzstatic.com\/image\/thumb\/Music\/v4\/cb\/d9\/e8\/cbd9e827-245b-76cf-89e3-f6799a6494ce\/AMT3-8091.jpg\/1200x630bb.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abBenjamin Rojas y su Piano Bar\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-17506-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio545\/Mix_BenjaminRojas_pianobar.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio545\/Mix_BenjaminRojas_pianobar.mp3\">http:\/\/archive.org\/download\/AQPRadio545\/Mix_BenjaminRojas_pianobar.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBenjamin Rojas y su Piano Bar\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[922],"tags":[],"class_list":["post-17506","post","type-post","status-publish","format-standard","hentry","category-la-magia-del"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=17506"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17506\/revisions"}],"predecessor-version":[{"id":98308,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17506\/revisions\/98308"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=17506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=17506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=17506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}