{"id":17886,"date":"2025-01-07T19:57:03","date_gmt":"2025-01-07T19:57:03","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=17886"},"modified":"2026-06-29T12:58:53","modified_gmt":"2026-06-29T17:58:53","slug":"trio-celeste","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/17886","title":{"rendered":"Trio Celeste"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/www.chambermusicoc.org\/wp-content\/uploads\/2013\/07\/TC_Sitting_1060x935.jpeg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abTrio Celeste\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-17886-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio551\/Mix_TrioCeleste.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio551\/Mix_TrioCeleste.mp3\">http:\/\/archive.org\/download\/AQPRadio551\/Mix_TrioCeleste.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abTrio Celeste\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-17886","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=17886"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17886\/revisions"}],"predecessor-version":[{"id":85622,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/17886\/revisions\/85622"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=17886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=17886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=17886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}