{"id":18528,"date":"2025-03-11T11:05:13","date_gmt":"2025-03-11T11:05:13","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=18528"},"modified":"2026-06-29T12:51:12","modified_gmt":"2026-06-29T17:51:12","slug":"rolando-laserie","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/18528","title":{"rendered":"Rolando LaSerie"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/-fN8G8a4PhVk\/VekaibP_seI\/AAAAAAAAA4Q\/Lstqt1VWA8k\/s1600\/Rolando%2BLaserie-front.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abRolando LaSerie\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-18528-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio566\/Mix_RolandoLaSerie.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio566\/Mix_RolandoLaSerie.mp3\">http:\/\/archive.org\/download\/AQPRadio566\/Mix_RolandoLaSerie.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abRolando LaSerie\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-18528","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/18528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=18528"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/18528\/revisions"}],"predecessor-version":[{"id":85068,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/18528\/revisions\/85068"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=18528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=18528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=18528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}