{"id":18538,"date":"2025-03-12T13:03:44","date_gmt":"2025-03-12T13:03:44","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=18538"},"modified":"2026-06-29T12:50:55","modified_gmt":"2026-06-29T17:50:55","slug":"tito-rodriguez-antologia-6","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/18538","title":{"rendered":"Tito Rodr\u00edguez &#8211; Antologia 6"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/4.bp.blogspot.com\/-jsQx_hQu5GQ\/UyV6htoeMyI\/AAAAAAAAC64\/Zci_p9NlKFs\/s1600\/titorodriguez-sepia4.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abTito Rodr\u00edguez &#8211; Antologia 6\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-18538-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio566\/Mix_TitoRodriguez_Antologia6.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio566\/Mix_TitoRodriguez_Antologia6.mp3\">http:\/\/archive.org\/download\/AQPRadio566\/Mix_TitoRodriguez_Antologia6.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abTito Rodr\u00edguez &#8211; Antologia 6\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-18538","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/18538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=18538"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/18538\/revisions"}],"predecessor-version":[{"id":85053,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/18538\/revisions\/85053"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=18538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=18538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=18538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}