{"id":1926,"date":"2024-08-01T02:45:40","date_gmt":"2024-08-01T02:45:40","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=1926"},"modified":"2026-06-29T13:24:32","modified_gmt":"2026-06-29T18:24:32","slug":"mix-frank-shackfield-interpreta-temas-de-tv","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/1926","title":{"rendered":"Mix Frank Shackfield interpreta temas de TV"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/mQNAYdvbPbc\/maxresdefault.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abMix Frank Shackfield interpreta temas de TV\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-1926-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio142\/Frank_Shackfield_TvThemes.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio142\/Frank_Shackfield_TvThemes.mp3\">http:\/\/www.archive.org\/download\/AQPRadio142\/Frank_Shackfield_TvThemes.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Frank Shackfield interpreta temas de TV\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[914],"tags":[],"class_list":["post-1926","post","type-post","status-publish","format-standard","hentry","category-tv-film"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=1926"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1926\/revisions"}],"predecessor-version":[{"id":86716,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1926\/revisions\/86716"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=1926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=1926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=1926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}