{"id":1961,"date":"2024-08-06T05:57:18","date_gmt":"2024-08-06T05:57:18","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=1961"},"modified":"2026-06-29T13:23:48","modified_gmt":"2026-06-29T18:23:48","slug":"baul-de-los-recuerdos-oscar-dleon","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/1961","title":{"rendered":"Ba\u00fal de los Recuerdos &#8211; Oscar dLe\u00f3n"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/_Vhs1nM6Vxhc\/SgMb0cwoLDI\/AAAAAAAACaA\/kmeepa02JIQ\/s400\/Oscar+D%27Leon+-+Autentico+-+1991-400.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abBa\u00fal de los Recuerdos &#8211; Oscar dLe\u00f3n\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-1961-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio144\/BR_OscardLeon1.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio144\/BR_OscardLeon1.mp3\">http:\/\/www.archive.org\/download\/AQPRadio144\/BR_OscardLeon1.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBa\u00fal de los Recuerdos &#8211; Oscar dLe\u00f3n\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-1961","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=1961"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1961\/revisions"}],"predecessor-version":[{"id":86687,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/1961\/revisions\/86687"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=1961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=1961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=1961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}