{"id":21006,"date":"2025-05-11T08:49:58","date_gmt":"2025-05-11T08:49:58","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=21006"},"modified":"2026-06-29T12:38:58","modified_gmt":"2026-06-29T17:38:58","slug":"jose-jose-antologia-4-1971","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/21006","title":{"rendered":"Jos\u00e9 Jos\u00e9 &#8211; Antologia 4 &#8211; 1971"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/cdn2.uvnimg.com\/3c\/69\/bfba1cd542589ff859e89cb752e2\/JoseJose04.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abJos\u00e9 Jos\u00e9 &#8211; Antologia 4 &#8211; 1971\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-21006-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio578\/Mix_JoseJose_Antologia4_1971.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio578\/Mix_JoseJose_Antologia4_1971.mp3\">http:\/\/archive.org\/download\/AQPRadio578\/Mix_JoseJose_Antologia4_1971.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abJos\u00e9 Jos\u00e9 &#8211; Antologia 4 &#8211; 1971\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-21006","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=21006"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21006\/revisions"}],"predecessor-version":[{"id":84279,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21006\/revisions\/84279"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=21006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=21006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=21006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}