{"id":21186,"date":"2025-06-01T16:55:25","date_gmt":"2025-06-01T16:55:25","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=21186"},"modified":"2026-08-12T20:34:47","modified_gmt":"2026-08-13T01:34:47","slug":"jose-jose-antologia-10-1974","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/21186","title":{"rendered":"Jos\u00e9 Jos\u00e9 &#8211; Antolog\u00eda 10 &#8211; 1974"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/1AQPRadio_revive2.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abJos\u00e9 Jos\u00e9 &#8211; Antolog\u00eda 10 &#8211; 1974\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-21186-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio581\/Mix_JoseJose_Antologia10_1974.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio581\/Mix_JoseJose_Antologia10_1974.mp3\">http:\/\/archive.org\/download\/AQPRadio581\/Mix_JoseJose_Antologia10_1974.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abJos\u00e9 Jos\u00e9 &#8211; Antolog\u00eda 10 &#8211; 1974\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-21186","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=21186"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21186\/revisions"}],"predecessor-version":[{"id":96491,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21186\/revisions\/96491"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=21186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=21186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=21186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}