{"id":21548,"date":"2025-07-04T15:13:33","date_gmt":"2025-07-04T15:13:33","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=21548"},"modified":"2026-06-29T10:57:58","modified_gmt":"2026-06-29T15:57:58","slug":"mix-todomezclado-165","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/21548","title":{"rendered":"Mix Todomezclado 165"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/3Ddq9-cXb_w\/maxresdefault.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abMix Todomezclado 165\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-21548-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio590\/Mix_Todomezclado165.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio590\/Mix_Todomezclado165.mp3\">http:\/\/archive.org\/download\/AQPRadio590\/Mix_Todomezclado165.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Todomezclado 165\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-21548","post","type-post","status-publish","format-standard","hentry","category-todo-mezclado"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=21548"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21548\/revisions"}],"predecessor-version":[{"id":83716,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21548\/revisions\/83716"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=21548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=21548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=21548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}