{"id":21554,"date":"2025-07-05T10:58:11","date_gmt":"2025-07-05T10:58:11","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=21554"},"modified":"2026-06-29T10:57:53","modified_gmt":"2026-06-29T15:57:53","slug":"jose-jose-antologia-20-1984","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/21554","title":{"rendered":"Jose Jose &#8211; Antologia 20 &#8211; 1984"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/xaqp20.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abJose Jose &#8211; Antologia 20 &#8211; 1984\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-21554-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio590\/Mix_JoseJose_Antologia20_1984.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio590\/Mix_JoseJose_Antologia20_1984.mp3\">http:\/\/archive.org\/download\/AQPRadio590\/Mix_JoseJose_Antologia20_1984.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abJose Jose &#8211; Antologia 20 &#8211; 1984\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-21554","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=21554"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21554\/revisions"}],"predecessor-version":[{"id":83709,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21554\/revisions\/83709"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=21554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=21554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=21554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}