{"id":21712,"date":"2025-01-14T01:35:01","date_gmt":"2025-01-14T01:35:01","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=2921"},"modified":"2026-06-29T12:58:21","modified_gmt":"2026-06-29T17:58:21","slug":"baul-de-los-recuerdos-salonorchester-coelln-2","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/21712","title":{"rendered":"Ba\u00fal de los Recuerdos &#8211; Salon Orchester Coelln"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/xaqp14.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abBa\u00fal de los Recuerdos &#8211; Salonorchester Coelln\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-21712-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio206\/BR_SalonorchesterCoelln.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio206\/BR_SalonorchesterCoelln.mp3\">http:\/\/www.archive.org\/download\/AQPRadio206\/BR_SalonorchesterCoelln.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBa\u00fal de los Recuerdos &#8211; Salonorchester Coelln\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-21712","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=21712"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21712\/revisions"}],"predecessor-version":[{"id":85577,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/21712\/revisions\/85577"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=21712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=21712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=21712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}