{"id":2367,"date":"2024-10-09T01:15:44","date_gmt":"2024-10-09T01:15:44","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=2367"},"modified":"2026-06-29T13:16:43","modified_gmt":"2026-06-29T18:16:43","slug":"baul-de-los-recuerdos-instrumentales-de-los-70s","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/2367","title":{"rendered":"Ba\u00fal de los Recuerdos &#8211; Instrumentales de los 70s"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/encrypted-tbn0.gstatic.com\/images?q=tbn:ANd9GcQ5A0IAca56kYLZC5i5Pn9foVWCJEHL0aJo5mGMMX7XpbSpdzASEA\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abBa\u00fal de los Recuerdos &#8211; Instrumentales de los 70s\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2367-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio169\/BR_Instrumentales70s.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio169\/BR_Instrumentales70s.mp3\">http:\/\/www.archive.org\/download\/AQPRadio169\/BR_Instrumentales70s.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBa\u00fal de los Recuerdos &#8211; Instrumentales de los 70s\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-2367","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/2367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=2367"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/2367\/revisions"}],"predecessor-version":[{"id":86288,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/2367\/revisions\/86288"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=2367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=2367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=2367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}