{"id":24288,"date":"2024-06-19T20:12:56","date_gmt":"2024-06-19T20:12:56","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=24288"},"modified":"2026-06-29T13:28:18","modified_gmt":"2026-06-29T18:28:18","slug":"sucedio-en-los-90s-12","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/24288","title":{"rendered":"Sucedi\u00f3 en los 90s &#8211; 12"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/ac.bluekea.com\/portfolionatural\/multimedia\/img_fondo\/fotos\/0_112.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abSucedi\u00f3 en los 90s &#8211; 12\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-24288-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio604\/sucedioenlos90s_12.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio604\/sucedioenlos90s_12.mp3\">https:\/\/archive.org\/download\/AQPRadio604\/sucedioenlos90s_12.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSucedi\u00f3 en los 90s &#8211; 12\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-24288","post","type-post","status-publish","format-standard","hentry","category-sucedio-en-los"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=24288"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24288\/revisions"}],"predecessor-version":[{"id":86950,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24288\/revisions\/86950"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=24288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=24288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=24288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}