{"id":24605,"date":"2024-07-19T18:20:59","date_gmt":"2024-07-19T18:20:59","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=24605"},"modified":"2026-06-29T13:25:46","modified_gmt":"2026-06-29T18:25:46","slug":"the-brass-ring","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/24605","title":{"rendered":"The Brass Ring"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/farm3.staticflickr.com\/2910\/13956390716_13db52e23c_b.jpg\" width = \"98%\" align=\"center\"> <\/p>\n<p>\u00abThe Brass Ring\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-24605-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio609\/Mix_BrassRing.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio609\/Mix_BrassRing.mp3\">https:\/\/archive.org\/download\/AQPRadio609\/Mix_BrassRing.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abThe Brass Ring\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-24605","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=24605"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24605\/revisions"}],"predecessor-version":[{"id":86784,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24605\/revisions\/86784"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=24605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=24605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=24605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}