{"id":24803,"date":"2024-08-12T07:42:19","date_gmt":"2024-08-12T07:42:19","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=24803"},"modified":"2026-08-12T20:58:14","modified_gmt":"2026-08-13T01:58:14","slug":"mix-todomezclado-209","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/24803","title":{"rendered":"Mix Todomezclado 209"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/-FBdPjjfYriw\/VIM2scQV0hI\/AAAAAAAABsY\/NnmgLvGfaRw\/s1600\/IMG_0793.JPG\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abMix Todomezclado 209\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-24803-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio614\/Mix_Todomezclado209.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio614\/Mix_Todomezclado209.mp3\">https:\/\/archive.org\/download\/AQPRadio614\/Mix_Todomezclado209.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Todomezclado 209\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-24803","post","type-post","status-publish","format-standard","hentry","category-todo-mezclado"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=24803"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24803\/revisions"}],"predecessor-version":[{"id":99068,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/24803\/revisions\/99068"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=24803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=24803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=24803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}