{"id":26776,"date":"2024-10-08T23:57:01","date_gmt":"2024-10-08T23:57:01","guid":{"rendered":"https:\/\/www.aqpradios.com\/musicaenlinea\/?p=26776"},"modified":"2026-06-29T13:16:45","modified_gmt":"2026-06-29T18:16:45","slug":"sandro-antologia-9-1969","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/26776","title":{"rendered":"Sandro &#8211; Antolog\u00eda 9 &#8211; 1969"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/cultivafuturo.com\/wp-content\/uploads\/2022\/03\/Flores-hermosas-que-no-son-pet-friendly-scaled.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abSandro &#8211; Antolog\u00eda 9 &#8211; 1969\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-26776-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio621\/Mix_Sandro_Antologia9_1969.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio621\/Mix_Sandro_Antologia9_1969.mp3\">https:\/\/archive.org\/download\/AQPRadio621\/Mix_Sandro_Antologia9_1969.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSandro &#8211; Antolog\u00eda 9 &#8211; 1969\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[4,83],"tags":[812,119,131,109],"class_list":["post-26776","post","type-post","status-publish","format-standard","hentry","category-baladas","category-baul-de-los-recuerdos","tag-baladas","tag-canciones-del-ayer","tag-canciones-del-recuerdo","tag-musica-en-linea"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/26776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=26776"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/26776\/revisions"}],"predecessor-version":[{"id":86290,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/26776\/revisions\/86290"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=26776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=26776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=26776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}