{"id":27265,"date":"2025-02-02T12:39:15","date_gmt":"2025-02-02T12:39:15","guid":{"rendered":"https:\/\/www.aqpradios.com\/musicaenlinea\/?p=27265"},"modified":"2026-08-12T20:47:11","modified_gmt":"2026-08-13T01:47:11","slug":"leo-dan-antologia-1","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/27265","title":{"rendered":"Leo Dan &#8211; Antolog\u00eda &#8211; 1"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/cloud10.todocoleccion.online\/discos-vinilo\/tc\/2016\/01\/09\/18\/53696014.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abLeo Dan &#8211; Antolog\u00eda &#8211; 1\u00bb<\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-27265-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio632\/Mix_LeoDan_Antologia1.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio632\/Mix_LeoDan_Antologia1.mp3\">https:\/\/archive.org\/download\/AQPRadio632\/Mix_LeoDan_Antologia1.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLeo Dan &#8211; Antolog\u00eda &#8211; 1\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[4,83],"tags":[134,812,119,131,109],"class_list":["post-27265","post","type-post","status-publish","format-standard","hentry","category-baladas","category-baul-de-los-recuerdos","tag-60s","tag-baladas","tag-canciones-del-ayer","tag-canciones-del-recuerdo","tag-musica-en-linea"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=27265"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27265\/revisions"}],"predecessor-version":[{"id":97849,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27265\/revisions\/97849"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=27265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=27265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=27265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}