{"id":27451,"date":"2025-03-17T12:56:25","date_gmt":"2025-03-17T12:56:25","guid":{"rendered":"https:\/\/www.aqpradios.com\/musicaenlinea\/?p=27451"},"modified":"2026-06-29T12:49:52","modified_gmt":"2026-06-29T17:49:52","slug":"la-magia-del-saxo-7","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/27451","title":{"rendered":"La M\u00e1gia del Saxo &#8211; 7"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/musicalexpress.com.pe\/wp-content\/uploads\/2025\/04\/Saxo-Boston-Dorado.webp\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abLa M\u00e1gia del Saxo &#8211; 7\u00bb<\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-27451-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio636\/Mix_LaMagiadelSaxo_7.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio636\/Mix_LaMagiadelSaxo_7.mp3\">https:\/\/archive.org\/download\/AQPRadio636\/Mix_LaMagiadelSaxo_7.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLa M\u00e1gia del Saxo &#8211; 7\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[922],"tags":[533,195,109,251,313],"class_list":["post-27451","post","type-post","status-publish","format-standard","hentry","category-la-magia-del","tag-instrumental","tag-instrumentales","tag-musica-en-linea","tag-sax","tag-saxo"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=27451"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27451\/revisions"}],"predecessor-version":[{"id":83462,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27451\/revisions\/83462"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=27451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=27451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=27451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}