{"id":27474,"date":"2025-03-21T17:09:04","date_gmt":"2025-03-21T17:09:04","guid":{"rendered":"https:\/\/www.aqpradios.com\/musicaenlinea\/?p=27474"},"modified":"2026-06-29T12:49:08","modified_gmt":"2026-06-29T17:49:08","slug":"mix-ecos-del-ayer-21","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/27474","title":{"rendered":"Mix Ecos del Ayer &#8211; 21"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/thumbs.dreamstime.com\/b\/primer-plano-de-un-reloj-arena-con-brillante-en-el-interior-imagen-conceptual-del-tiempo-dise%C3%B1o-d-realizado-partir-fotograf%C3%ADa-414797699.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abMix Ecos del Ayer &#8211; 21\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-27474-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio637\/Mix_EcosdelAyer_21.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio637\/Mix_EcosdelAyer_21.mp3\">https:\/\/archive.org\/download\/AQPRadio637\/Mix_EcosdelAyer_21.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Ecos del Ayer &#8211; 21\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[812,119,131,109,614],"class_list":["post-27474","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos","tag-baladas","tag-canciones-del-ayer","tag-canciones-del-recuerdo","tag-musica-en-linea","tag-romanticas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=27474"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27474\/revisions"}],"predecessor-version":[{"id":84933,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27474\/revisions\/84933"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=27474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=27474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=27474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}