{"id":27765,"date":"2025-05-01T21:53:16","date_gmt":"2025-05-01T21:53:16","guid":{"rendered":"https:\/\/www.aqpradios.com\/musicaenlinea\/?p=27765"},"modified":"2026-08-12T20:37:50","modified_gmt":"2026-08-13T01:37:50","slug":"mix-todomezclado-262","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/27765","title":{"rendered":"Mix Todomezclado 263"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/cdn-images.dzcdn.net\/images\/artist\/5d0355a0dd224843b5f0a3196a7b9e05\/1900x1900-000000-80-0-0.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abMix Todomezclado 263\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-27765-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio641\/Mix_Todomezclado263.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio641\/Mix_Todomezclado263.mp3\">https:\/\/archive.org\/download\/AQPRadio641\/Mix_Todomezclado263.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Todomezclado 263\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-27765","post","type-post","status-publish","format-standard","hentry","category-todo-mezclado"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=27765"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27765\/revisions"}],"predecessor-version":[{"id":96837,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27765\/revisions\/96837"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=27765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=27765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=27765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}