{"id":27999,"date":"2025-06-12T05:40:29","date_gmt":"2025-06-12T05:40:29","guid":{"rendered":"https:\/\/www.aqpradios.com\/musicaenlinea\/?p=27999"},"modified":"2026-06-29T11:00:32","modified_gmt":"2026-06-29T16:00:32","slug":"sucedio-en-los-70s-105","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/27999","title":{"rendered":"Sucedi\u00f3 en los 70s -105"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/media.metrolatam.com\/2019\/11\/08\/q2dwefergvrbthty-a1fd6e6aab93f8fa7c6cebe02cb01f67-1200x800.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abSucedi\u00f3 en los 70s -105\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-27999-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio645\/sucedioenlos70s_105.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio645\/sucedioenlos70s_105.mp3\">https:\/\/archive.org\/download\/AQPRadio645\/sucedioenlos70s_105.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSucedi\u00f3 en los 70s -105\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[5,10],"tags":[21,152,119,131,49,109,122],"class_list":["post-27999","post","type-post","status-publish","format-standard","hentry","category-musica-disco-soul","category-sucedio-en-los","tag-70s","tag-bailables","tag-canciones-del-ayer","tag-canciones-del-recuerdo","tag-funky-music","tag-musica-en-linea","tag-pop"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=27999"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27999\/revisions"}],"predecessor-version":[{"id":83903,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/27999\/revisions\/83903"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=27999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=27999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=27999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}