{"id":2931,"date":"2025-01-15T14:30:51","date_gmt":"2025-01-15T14:30:51","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=2931"},"modified":"2026-08-12T20:48:19","modified_gmt":"2026-08-13T01:48:19","slug":"jackie-gleason-2","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/2931","title":{"rendered":"Jackie Gleason 2"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/musicrewind.com\/images\/products\/9995.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abJackie Gleason 2\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2931-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio207\/BR_JackieGleason2.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio207\/BR_JackieGleason2.mp3\">http:\/\/www.archive.org\/download\/AQPRadio207\/BR_JackieGleason2.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abJackie Gleason 2\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-2931","post","type-post","status-publish","format-standard","hentry","category-musica-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/2931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=2931"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/2931\/revisions"}],"predecessor-version":[{"id":97984,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/2931\/revisions\/97984"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=2931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=2931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}