{"id":29581,"date":"2025-09-10T17:35:45","date_gmt":"2025-09-10T22:35:45","guid":{"rendered":"https:\/\/www.aqpradios.com\/musicaenlinea\/?p=29581"},"modified":"2026-06-29T10:49:53","modified_gmt":"2026-06-29T15:49:53","slug":"sucedio-en-los-70s-121","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/29581","title":{"rendered":"Sucedi\u00f3 en los 70s &#8211; 121"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/fotografias.antena3.com\/clipping\/cmsimages01\/2017\/09\/18\/36D0EC74-7F2D-4225-A121-0A1265E10214\/58.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abSucedi\u00f3 en los 70s &#8211; 121\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melod\u00edas que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-29581-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio654\/sucedioenlos70s_121.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio654\/sucedioenlos70s_121.mp3\">https:\/\/archive.org\/download\/AQPRadio654\/sucedioenlos70s_121.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSucedi\u00f3 en los 70s &#8211; 121\u00bb Active el Player de Sonido para que goce con las dulces melod\u00edas que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-29581","post","type-post","status-publish","format-standard","hentry","category-sucedio-en-los"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/29581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=29581"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/29581\/revisions"}],"predecessor-version":[{"id":83197,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/29581\/revisions\/83197"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=29581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=29581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=29581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}