{"id":3066,"date":"2025-02-04T09:31:13","date_gmt":"2025-02-04T09:31:13","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=3066"},"modified":"2026-06-29T12:56:17","modified_gmt":"2026-06-29T17:56:17","slug":"baul-de-los-recuerdos-donna-summer-in-live","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/3066","title":{"rendered":"Ba\u00fal de los Recuerdos &#8211; Donna Summer in Live"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/-JkC_hc5bKbQ\/TVv9vbxuapI\/AAAAAAAAA8Q\/yYG1XXdsHYk\/s1600\/donna-summer.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abBa\u00fal de los Recuerdos &#8211; Donna Summer en Vivo\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><audio class=\"wp-audio-shortcode\" id=\"audio-3066-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio211\/BR_DonnaSummer_Live.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio211\/BR_DonnaSummer_Live.mp3\">http:\/\/www.archive.org\/download\/AQPRadio211\/BR_DonnaSummer_Live.mp3<\/a><\/audio><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abBa\u00fal de los Recuerdos &#8211; Donna Summer en Vivo\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-3066","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/3066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=3066"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/3066\/revisions"}],"predecessor-version":[{"id":85417,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/3066\/revisions\/85417"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=3066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=3066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=3066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}