{"id":31,"date":"2023-12-20T15:57:37","date_gmt":"2023-12-20T15:57:37","guid":{"rendered":"http:\/\/dulcesmelodias.xtreemhost.com\/?p=31"},"modified":"2026-06-29T13:34:37","modified_gmt":"2026-06-29T18:34:37","slug":"mix-orquestado-40","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/31","title":{"rendered":"Mix Orquestado 40"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/media-cdn.tripadvisor.com\/media\/photo-s\/01\/7d\/ce\/e8\/bellas-artes.jpg\" width=\"98%\" align=\"center\"><br \/>\n \u00abMix Orquestada 40\u00bb <audio class=\"wp-audio-shortcode\" id=\"audio-31-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio42\/MixOrquestada40.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio42\/MixOrquestada40.mp3\">http:\/\/www.archive.org\/download\/AQPRadio42\/MixOrquestada40.mp3<\/a><\/audio><br \/>\nActive el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Orquestada 40\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-31","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"predecessor-version":[{"id":87316,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/31\/revisions\/87316"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}