{"id":33766,"date":"2023-10-14T17:56:52","date_gmt":"2023-10-14T22:56:52","guid":{"rendered":"https:\/\/aqpradios.com\/actual\/?p=33766"},"modified":"2026-06-29T13:36:38","modified_gmt":"2026-06-29T18:36:38","slug":"mix-relax-252","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/33766","title":{"rendered":"MIX Relax 252"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/previews.123rf.com\/images\/dolgachov\/dolgachov1612\/dolgachov161200530\/66757226-concepto-de-personas-tecnolog%C3%ADa-relax-y-ocio-feliz-mujer-joven-asi%C3%A1tica-tumbado-en-el-sof%C3%A1-con.jpg\" width=\"98%\" align=\"middle\" \/><\/p>\n<p>\u00abMIX Relax 252\u00bb<\/p>\n<p>Active el Player de Sonido para que goce con las dulces melod\u00edas que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-33766-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/archive.org\/download\/AQPRadio660\/MixRelax252.mp3?_=1\" \/><a href=\"https:\/\/archive.org\/download\/AQPRadio660\/MixRelax252.mp3\">https:\/\/archive.org\/download\/AQPRadio660\/MixRelax252.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMIX Relax 252\u00bb Active el Player de Sonido para que goce con las dulces melod\u00edas que les brindamos. Fina cortes\u00eda de AQPRadio. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[12],"tags":[533,195,811,68],"class_list":["post-33766","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-instrumental","tag-instrumentales","tag-musica-orquestada","tag-orquestadas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/33766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=33766"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/33766\/revisions"}],"predecessor-version":[{"id":87443,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/33766\/revisions\/87443"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=33766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=33766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=33766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}