{"id":3679,"date":"2025-02-19T01:36:33","date_gmt":"2025-02-19T01:36:33","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=3679"},"modified":"2026-06-29T12:54:48","modified_gmt":"2026-06-29T17:54:48","slug":"franz-lambert-orchestra-3","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/3679","title":{"rendered":"Franz Lambert &#038; Orchestra &#8211; 3"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/4.bp.blogspot.com\/-W1fJTUjwLss\/Tq1DuE6cNEI\/AAAAAAAAIxs\/g_wuHQy4a9E\/s400\/folder.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abRay Davies &#8211; Tv Themes\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><audio class=\"wp-audio-shortcode\" id=\"audio-3679-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio222\/Mix_FranzLambert3.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio222\/Mix_FranzLambert3.mp3\">http:\/\/www.archive.org\/download\/AQPRadio222\/Mix_FranzLambert3.mp3<\/a><\/audio><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abRay Davies &#8211; Tv Themes\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-3679","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/3679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=3679"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/3679\/revisions"}],"predecessor-version":[{"id":85302,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/3679\/revisions\/85302"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=3679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=3679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=3679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}