{"id":4084,"date":"2025-06-05T13:26:58","date_gmt":"2025-06-05T13:26:58","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=4084"},"modified":"2026-06-29T11:01:50","modified_gmt":"2026-06-29T16:01:50","slug":"todo-mezclado-3","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/4084","title":{"rendered":"Todo Mezclado 3"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/t2.ftcdn.net\/jpg\/00\/03\/16\/61\/400_F_3166125_eIf3HIfCi5KpDj7Lrj6UrFk8V1Gme1.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abTodo Mezclado 3\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-4084-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio241\/Mix_Todomezclado3.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio241\/Mix_Todomezclado3.mp3\">http:\/\/www.archive.org\/download\/AQPRadio241\/Mix_Todomezclado3.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abTodo Mezclado 3\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-4084","post","type-post","status-publish","format-standard","hentry","category-todo-mezclado"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=4084"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4084\/revisions"}],"predecessor-version":[{"id":83993,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4084\/revisions\/83993"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=4084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=4084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=4084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}