{"id":4092,"date":"2025-06-07T15:19:35","date_gmt":"2025-06-07T15:19:35","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=4092"},"modified":"2026-06-29T11:01:27","modified_gmt":"2026-06-29T16:01:27","slug":"todo-mezclado-5","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/4092","title":{"rendered":"Todo Mezclado 5"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/escuchandoaqpradio17.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abTodo Mezclado 5\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-4092-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio241\/Mix_Todomezclado5.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio241\/Mix_Todomezclado5.mp3\">http:\/\/www.archive.org\/download\/AQPRadio241\/Mix_Todomezclado5.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abTodo Mezclado 5\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-4092","post","type-post","status-publish","format-standard","hentry","category-todo-mezclado"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=4092"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4092\/revisions"}],"predecessor-version":[{"id":83965,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4092\/revisions\/83965"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=4092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=4092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=4092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}