{"id":4372,"date":"2025-05-29T19:47:23","date_gmt":"2025-05-29T19:47:23","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=4372"},"modified":"2026-08-12T20:35:05","modified_gmt":"2026-08-13T01:35:05","slug":"leyendas-de-la-fania-1","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/4372","title":{"rendered":"Leyendas de la Fania &#8211; 1"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/aqpradios.com\/actual\/imagenaqp\/xaqp18.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p> \u00abLeyendas de la Fania &#8211; 1\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-4372-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio249\/Mix_LeyendasdelaFania_1.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio249\/Mix_LeyendasdelaFania_1.mp3\">http:\/\/archive.org\/download\/AQPRadio249\/Mix_LeyendasdelaFania_1.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLeyendas de la Fania &#8211; 1\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-4372","post","type-post","status-publish","format-standard","hentry","category-salsa"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=4372"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4372\/revisions"}],"predecessor-version":[{"id":96524,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4372\/revisions\/96524"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=4372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=4372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=4372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}