{"id":4398,"date":"2025-06-04T12:31:18","date_gmt":"2025-06-04T12:31:18","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=4398"},"modified":"2026-06-29T11:02:02","modified_gmt":"2026-06-29T16:02:02","slug":"tiempo-de-fiesta-a-ritmo-de-salsa-22","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/4398","title":{"rendered":"Tiempo de Fiesta a Ritmo de Salsa \u2013 22"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/_ZMxflffvm4k\/SYh5hDQAZvI\/AAAAAAAAAJc\/KShmwvMjW60\/s400\/11+~+Marta+bailando+salsa+%282%29.JPG\" width=\"98%\" align=\"center\"><\/p>\n<p> \u00abTiempo de Fiesta a Ritmo de Salsa \u2013 22\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-4398-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio250\/Mix_Bailecitos22.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio250\/Mix_Bailecitos22.mp3\">http:\/\/archive.org\/download\/AQPRadio250\/Mix_Bailecitos22.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abTiempo de Fiesta a Ritmo de Salsa \u2013 22\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-4398","post","type-post","status-publish","format-standard","hentry","category-salsa"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=4398"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4398\/revisions"}],"predecessor-version":[{"id":84007,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4398\/revisions\/84007"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=4398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=4398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=4398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}