{"id":4495,"date":"2025-08-08T04:10:48","date_gmt":"2025-08-08T04:10:48","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=4495"},"modified":"2026-06-29T10:54:35","modified_gmt":"2026-06-29T15:54:35","slug":"frank-chacksfield-orchestra-5","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/4495","title":{"rendered":"Frank Chacksfield &#038; Orchestra &#8211; 5"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/songbook1.files.wordpress.com\/2011\/03\/frank-chacksfield-1954-presenting-cover.jpg\" width=\"98%\" align=\"center\"><br \/>\n \u00abFrank Chacksfield &#038; Orchestra &#8211; 5\u00bb <audio class=\"wp-audio-shortcode\" id=\"audio-4495-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio252\/Mix_FrankChacksfieldOrchestra5.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio252\/Mix_FrankChacksfieldOrchestra5.mp3\">http:\/\/archive.org\/download\/AQPRadio252\/Mix_FrankChacksfieldOrchestra5.mp3<\/a><\/audio> Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abFrank Chacksfield &#038; Orchestra &#8211; 5\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4495","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=4495"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4495\/revisions"}],"predecessor-version":[{"id":83457,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/4495\/revisions\/83457"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=4495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=4495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=4495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}