{"id":5013,"date":"2023-03-26T14:30:34","date_gmt":"2023-03-26T14:30:34","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=5013"},"modified":"2026-06-29T17:57:51","modified_gmt":"2026-06-29T22:57:51","slug":"mix-boleros-11","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/5013","title":{"rendered":"Mix Boleros &#8211; 11"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/2.bp.blogspot.com\/-zkAC7NsK_Gk\/TzKDsM-LC2I\/AAAAAAAADMg\/udm3JZEscMQ\/s1600\/viejitos-tangueros-web.jpg\" width=\"98%\" align=\"center\"><br \/>\n \u00abMix Boleros &#8211; 11\u00bb <audio class=\"wp-audio-shortcode\" id=\"audio-5013-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio273\/MixBoleros11.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio273\/MixBoleros11.mp3\">http:\/\/archive.org\/download\/AQPRadio273\/MixBoleros11.mp3<\/a><\/audio> Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Boleros &#8211; 11\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[71],"tags":[],"class_list":["post-5013","post","type-post","status-publish","format-standard","hentry","category-boleros"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=5013"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5013\/revisions"}],"predecessor-version":[{"id":88572,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5013\/revisions\/88572"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=5013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=5013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=5013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}