{"id":5625,"date":"2023-06-26T04:39:41","date_gmt":"2023-06-26T04:39:41","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=5625"},"modified":"2026-06-29T13:43:37","modified_gmt":"2026-06-29T18:43:37","slug":"raphael-en-1962-1963","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/5625","title":{"rendered":"Raphael en 1962 &#038; 1963"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/elsoldelaflorida.com\/wp-content\/uploads\/2012\/06\/raphael-01.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abRaphael en 1962 &#038; 1963\u00bb<\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-5625-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio295\/Mix_Raphael_1962_1963.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio295\/Mix_Raphael_1962_1963.mp3\">http:\/\/archive.org\/download\/AQPRadio295\/Mix_Raphael_1962_1963.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abRaphael en 1962 &#038; 1963\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[920],"tags":[],"class_list":["post-5625","post","type-post","status-publish","format-standard","hentry","category-rap"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=5625"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5625\/revisions"}],"predecessor-version":[{"id":87867,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5625\/revisions\/87867"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=5625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=5625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=5625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}