{"id":563,"date":"2024-01-27T13:31:12","date_gmt":"2024-01-27T13:31:12","guid":{"rendered":"http:\/\/dulcesmelodias.xtreemhost.com\/?p=563"},"modified":"2026-06-29T13:33:01","modified_gmt":"2026-06-29T18:33:01","slug":"mix-orquestada-72","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/563","title":{"rendered":"Mix Orquestada &#8211; 72"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/relaxingatspa.files.wordpress.com\/2010\/09\/54326891b544815a_relax.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p> \u00abMix Orquestada &#8211; 72\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-563-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio66\/MixOrquestada72.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio66\/MixOrquestada72.mp3\">http:\/\/www.archive.org\/download\/AQPRadio66\/MixOrquestada72.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Orquestada &#8211; 72\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-563","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=563"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/563\/revisions"}],"predecessor-version":[{"id":87243,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/563\/revisions\/87243"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}