{"id":57,"date":"2023-12-30T01:24:48","date_gmt":"2023-12-30T01:24:48","guid":{"rendered":"http:\/\/dulcesmelodias.xtreemhost.com\/?p=57"},"modified":"2026-06-29T13:34:23","modified_gmt":"2026-06-29T18:34:23","slug":"mix-orquestado-14","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/57","title":{"rendered":"Mix Orquestado 14"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/img.freepik.com\/vector-gratis\/ilustracion-actuacion-banda-jazz_23-2149597416.jpg?semt=ais_hybrid&#038;w=740&#038;q=80\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abMix Orquestada 14\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-57-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio18\/MIXOrquestada14.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio18\/MIXOrquestada14.mp3\">http:\/\/www.archive.org\/download\/AQPRadio18\/MIXOrquestada14.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Orquestada 14\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-57","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/57\/revisions"}],"predecessor-version":[{"id":87298,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/57\/revisions\/87298"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=57"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=57"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}