{"id":5976,"date":"2023-08-31T16:10:15","date_gmt":"2023-08-31T16:10:15","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=5976"},"modified":"2026-06-29T13:37:47","modified_gmt":"2026-06-29T18:37:47","slug":"relax-45-chill-out","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/5976","title":{"rendered":"Relax 45 &#8211; Chill Out"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/1.bp.blogspot.com\/--0Ekicct2MQ\/T2YJoF5hLWI\/AAAAAAAAAu4\/9_weIN7dIZs\/s1600\/DSC04011.JPG\" width=\"98%\" align=\"center\"><\/p>\n<p> \u00abRelax 45 &#8211; Chill Out\u00bb <audio class=\"wp-audio-shortcode\" id=\"audio-5976-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio308\/MixRelax45.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio308\/MixRelax45.mp3\">http:\/\/archive.org\/download\/AQPRadio308\/MixRelax45.mp3<\/a><\/audio> Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abRelax 45 &#8211; Chill Out\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-5976","post","type-post","status-publish","format-standard","hentry","category-musica-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=5976"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5976\/revisions"}],"predecessor-version":[{"id":87528,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/5976\/revisions\/87528"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=5976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=5976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=5976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}